{"id":419,"date":"2017-11-29T11:02:34","date_gmt":"2017-11-29T11:02:34","guid":{"rendered":"http:\/\/docentes.fundacionginer.org\/?p=419"},"modified":"2017-12-01T13:49:12","modified_gmt":"2017-12-01T13:49:12","slug":"educacion-la-innovacion-pendiente-una-conversacion-entre-cristobal-cobo-y-carlos-magro","status":"publish","type":"post","link":"https:\/\/docentes.fundacionginer.org\/index.php\/2017\/11\/29\/educacion-la-innovacion-pendiente-una-conversacion-entre-cristobal-cobo-y-carlos-magro\/","title":{"rendered":"Educaci\u00f3n. la innovaci\u00f3n pendiente. Una conversaci\u00f3n entre Crist\u00f3bal Cobo y Carlos Magro"},"content":{"rendered":"<p>Hasta ahora los dispositivos han acaparado toda la atenci\u00f3n, pero los verdaderos cambios en la ense\u00f1anza y el aprendizaje han sido invisibles. Con la intenci\u00f3n de darles la visibilidad que merecen, el profesor e investigador <strong>Crist\u00f3bal Cobo<\/strong> nos invita a pensar en la educaci\u00f3n desde una nueva \u00f3ptica, una que plantea que la verdadera innovaci\u00f3n est\u00e1 en explorar nuevas formas de valorar y reconocer el conocimiento, tanto dentro como fuera del aula. Dado que la tecnolog\u00eda forma parte integral de nuestras vidas, esta reflexi\u00f3n trasciende el contexto educativo y parte de la base de que <strong>todo espacio se convierte en un entorno de aprendizaje.<\/strong><\/p>\n<p>Pero olvid\u00e9monos de encontrar f\u00f3rmulas en este trabajo. Al contrario, el gran aporte del autor consiste en <strong>analizar los desaf\u00edos que presentan las tecnolog\u00edas en la ense\u00f1anza<\/strong> y las redefiniciones de los conceptos saber y conocimiento en una sociedad que est\u00e1 en plena transformaci\u00f3n.<\/p>\n<div align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/4VGVeYzMd2I\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<div align=\"center\"><\/div>\n<p><strong>Puedes descargar &#8216;La Innovaci\u00f3n Pendiente&#8217; \u00a0<a href=\"http:\/\/docentes.fundacionginer.org\/wp-content\/uploads\/2017\/11\/La_innovacion_pendiente.pdf\">aqu\u00ed<\/a><\/strong><\/p>\n<p>Sin ofrecer recetas, este texto expone un an\u00e1lisis m\u00e1s detenido sobre los desaf\u00edos que generan las tecnolog\u00edas en la educaci\u00f3n y las definiciones conceptuales de lo que hoy significa saber y tener conocimiento sobre algo. Este no est\u00e1 restringido al aula ya que se ampl\u00eda de manera transversal a la vida social (tal cual es nuestro uso de las tecnolog\u00edas).<\/p>\n<p>Uno de los elementos m\u00e1s complejos de ser comprendidos, dada su intangibilidad, es el hecho de que la revoluci\u00f3n actual no es una revoluci\u00f3n de dispositivos, infraestructura, plataformas o canales de intercambio sino, m\u00e1s bien, plantea una resignificaci\u00f3n de sentido.<\/p>\n<p>A pesar de que son los dispositivos los que se llevan buena parte de la atenci\u00f3n en este tipo de discusiones, los cambios m\u00e1s sustantivos son invisibles. En otras palabras, el cambio m\u00e1s estructural no tiene relaci\u00f3n solo con pensar en los educadores desde una nueva \u00f3ptica.<\/p>\n<p>Tambi\u00e9n implica pensar en formadores que sean mucho m\u00e1s que facilitadores de tecnolog\u00eda. Es decir, reperfilar el papel de los docentes bajo una relaci\u00f3n diferente con el conocimiento. Una relaci\u00f3n distinta a la que tradicionalmente hab\u00edan tenido (y bajo la cual muchos fuimos formados). Esto significa que el valor central ya no est\u00e1 en el acceso o dominio de un conocimiento en particular sino en la capacidad de desfragmentar y reconstruir conocimientos bajo nuevas combinaciones, formatos y canales. Una resignificaci\u00f3n de lo que implica ofrecer y recibir educaci\u00f3n. El cambio de valor est\u00e1 en el conocimiento como tal, tanto por su acelerada renovaci\u00f3n, por la abundancia de posibilidades y canales que existen para acceder a \u00e9l, as\u00ed como por la posibilidad de hibridar contextos, disciplinas y enfoques. Todas estas posibilidades de una u otra forma se plasman en un cambio de rol tanto de las personas como de las instituciones que tradicionalmente han administrado el conocimiento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Crist\u00f3bal Cobo <\/strong>(19 de marzo de 1976) \u200b es un profesor e investigador en tecnolog\u00edas nuevas y educacionales, que ha trabajado en proyectos en Sudam\u00e9rica, Norteam\u00e9rica y Europa. Actualmente es un acad\u00e9mico e investigador asociado en el Instituto de Internet de Oxford, <u><sup>[][]<\/sup><\/u>adem\u00e1s asociado en el Centro de Habilidades, Conocimientos y Desempe\u00f1o Organizacional, parte de la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Universidad_de_Oxford\">Universidad de Oxford<\/a>. Su principal aportaci\u00f3n te\u00f3rica es el concepto de \u00abaprendizaje invisible\u00bb, promoviendo la idea de que el aprendizaje debe ser el resultado de la acci\u00f3n y la interacci\u00f3n, en lugar de a trav\u00e9s de la instrucci\u00f3n. El trabajo de Cobo en defensa de la publicaci\u00f3n cient\u00edfica de acceso abierto ha sido destacado en Europa y tambi\u00e9n en Am\u00e9rica Latina.<\/p>\n<p><strong>Carlos Magro<\/strong>, especialista en innovaci\u00f3n educativa, ha sido responsable del programa Ciencia y Sociedad de la Comunidad de Madrid, director de la Oficina de Informaci\u00f3n Cient\u00edfica de la Fundaci\u00f3n mi+d en la Consejer\u00eda de Educaci\u00f3n de la Comunidad de Madrid,\u00a0director de Innovaci\u00f3n y Comunicaci\u00f3n de la Escuela de Organizaci\u00f3n Industrial (EOI)\u00a0y director acad\u00e9mico del\u00a0Istituto Europeo di Design (IED Espa\u00f1a). Es vicepresidente de la Asociaci\u00f3n Educaci\u00f3n Abierta y trabaja como consultor independiente en proyectos de cambio educativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta ahora los dispositivos han acaparado toda la atenci\u00f3n, pero los verdaderos cambios en la ense\u00f1anza y el aprendizaje han sido invisibles. Con la intenci\u00f3n de darles la visibilidad que merecen, el profesor e investigador Crist\u00f3bal Cobo nos invita a pensar en la educaci\u00f3n desde una nueva \u00f3ptica, una que plantea que la verdadera innovaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[17,36,38,16],"_links":{"self":[{"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/posts\/419"}],"collection":[{"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/comments?post=419"}],"version-history":[{"count":15,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/posts\/419\/revisions"}],"predecessor-version":[{"id":444,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/posts\/419\/revisions\/444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/media\/435"}],"wp:attachment":[{"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/categories?post=419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/docentes.fundacionginer.org\/index.php\/wp-json\/wp\/v2\/tags?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}